{"id":4862,"date":"2023-10-21T10:20:59","date_gmt":"2023-10-21T13:20:59","guid":{"rendered":"https:\/\/calinense.com.br\/NOVOSITE\/?page_id=4862"},"modified":"2026-07-15T11:01:57","modified_gmt":"2026-07-15T14:01:57","slug":"ingressos","status":"publish","type":"page","link":"https:\/\/calinense.com.br\/NOVOSITE\/ingressos\/","title":{"rendered":"Ingressos"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4862\" class=\"elementor elementor-4862\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b907c5 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"3b907c5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1b4b008\" data-id=\"1b4b008\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-935707d elementor-widget elementor-widget-heading\" data-id=\"935707d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Ingressos<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25261d4 elementor-widget elementor-widget-text-editor\" data-id=\"25261d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Adquira seu ingresso para curtir os jogos do elefante da noroeste no Gilbert\u00e3o!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c682f80 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"c682f80\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2331cec\" data-id=\"2331cec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c180ca3 elementor-widget elementor-widget-heading\" data-id=\"c180ca3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Passaporte Ouro<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-668a246 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"668a246\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0455878\" data-id=\"0455878\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a948ff elementor-widget elementor-widget-image\" data-id=\"6a948ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"960\" height=\"960\" src=\"https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_ouro-1024x1024.png\" class=\"attachment-large size-large wp-image-4865\" alt=\"\" srcset=\"https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_ouro-1024x1024.png 1024w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_ouro-300x300.png 300w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_ouro-150x150.png 150w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_ouro-768x768.png 768w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_ouro-100x100.png 100w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_ouro-50x50.png 50w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_ouro-25x25.png 25w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_ouro-90x90.png 90w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_ouro.png 1080w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6ddb124\" data-id=\"6ddb124\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df9a34d elementor-widget elementor-widget-text-editor\" data-id=\"df9a34d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>JOGUE COM A GENTE!<\/strong><\/p><p>Chegou a hora torcedor, precisamos que seja um de nossos jogadores e apoie o Elefante no Paulist\u00e3o 2024.<\/p><p>Compre j\u00e1 seu PASSAPORTE OURO para todos os jogos do Linense em casa.<\/p><h2 style=\"margin-bottom: -2px;\"><strong>R$600,00<\/strong><\/h2><p><span style=\"margin-top: -20px;\">em at\u00e9 5x sem juros<\/span><br \/><br \/><\/p><p>O PASSAPORTE OURO dar\u00e1 a voc\u00ea o direito de ter <strong>uma cadeira com seu nome gravado<\/strong> na \u00e1rea coberta do est\u00e1dio e uma camisa oficial 2024.<\/p><p>O n\u00famero selecionado na compra ser\u00e1 o n\u00famero da cadeira que receber\u00e1 seu nome e ficar\u00e1 reservada exclusivamente para voc\u00ea durante todo o campeonato.<\/p><p style=\"text-align: left;\">Garanta j\u00e1 sua cadeira em at\u00e9 5x sem juros e retire seus ingressos e camisa oficial na secretaria do est\u00e1dio Gilbert\u00e3o a partir do dia 08\/01\/2024.<\/p><p><strong>Hor\u00e1rio de atendimento WhatsApp\/Secretaria:<\/strong> das 8h \u00e0s 18h &#8211; de segunda-feira a sexta-feira e das 8h \u00e0s 12h aos s\u00e1bados.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c52d6f elementor-align-left elementor-mobile-align-center elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"4c52d6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/CADEIRAS-2023_mapa_correcao.png\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-image\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver mapa de cadeiras<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fec9bd2 elementor-align-left elementor-mobile-align-center elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"fec9bd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/wa.me\/\/551435324467?text=Ola%2C%20tenho%20interesse%20em%20comprar%20o%20passaporte\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Comprar pelo WhatsApp<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-57fc35c elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"57fc35c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8cfcd1d\" data-id=\"8cfcd1d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-733b9f5 elementor-widget elementor-widget-heading\" data-id=\"733b9f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Passaporte Prata<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-50d9e75 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"50d9e75\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ac4f6f1\" data-id=\"ac4f6f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-551b035 elementor-widget elementor-widget-image\" data-id=\"551b035\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"960\" src=\"https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_prata-1024x1024.png\" class=\"attachment-large size-large wp-image-4881\" alt=\"\" srcset=\"https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_prata-1024x1024.png 1024w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_prata-300x300.png 300w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_prata-150x150.png 150w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_prata-768x768.png 768w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_prata-100x100.png 100w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_prata-50x50.png 50w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_prata-25x25.png 25w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_prata-90x90.png 90w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_prata.png 1080w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-170a3fd\" data-id=\"170a3fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d03a09 elementor-widget elementor-widget-text-editor\" data-id=\"0d03a09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Compre j\u00e1 seu PASSAPORTE PRATA para todos os jogos do Linense em casa.<\/p><h2 style=\"margin-bottom: -2px;\"><strong>R$210,00<\/strong><\/h2><p><span style=\"margin-top: -20px;\">em at\u00e9 5x sem juros<\/span><\/p><p>O PASSAPORTE PRATA dar\u00e1 a voc\u00ea o direito de assistir <strong>todos os jogos do elefante em casa no Paulist\u00e3o 2024 na \u00e1rea COBERTA do est\u00e1dio<\/strong>.<\/p><p style=\"text-align: left;\">Garanta j\u00e1 seus ingressos na secretaria do clube ou pelo WhatsApp!<\/p><p>A retirada de todos os ingressos estar\u00e1 dispon\u00edvel na secretaria do Gilbert\u00e3o a partir do dia 08\/01\/2024.<\/p><p><strong>Hor\u00e1rio de atendimento WhatsApp\/Secretaria:<\/strong> das 8h \u00e0s 18h &#8211; de segunda-feira a sexta-feira e das 8h \u00e0s 12h aos s\u00e1bados.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-432e078 elementor-align-left elementor-mobile-align-center elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"432e078\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/wa.me\/\/551435324467?text=Ola%2C%20tenho%20interesse%20em%20comprar%20o%20passaporte\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Comprar pelo WhatsApp<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0469d41 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"0469d41\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b2bfd98\" data-id=\"b2bfd98\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d47f34c elementor-widget elementor-widget-heading\" data-id=\"d47f34c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Passaporte Bronze<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6431c40 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6431c40\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-52c117c\" data-id=\"52c117c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f4ce47 elementor-widget elementor-widget-image\" data-id=\"0f4ce47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"960\" src=\"https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_bronze-1024x1024.png\" class=\"attachment-large size-large wp-image-4882\" alt=\"\" srcset=\"https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_bronze-1024x1024.png 1024w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_bronze-300x300.png 300w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_bronze-150x150.png 150w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_bronze-768x768.png 768w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_bronze-100x100.png 100w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_bronze-50x50.png 50w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_bronze-25x25.png 25w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_bronze-90x90.png 90w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/10\/cal_passaporte_bronze.png 1080w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3a108ec\" data-id=\"3a108ec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f992599 elementor-widget elementor-widget-text-editor\" data-id=\"f992599\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Compre j\u00e1 seu PASSAPORTE BRONZE para todos os jogos do Linense em casa.<\/p><h2 style=\"margin-bottom: -2px;\"><strong>R$140,00<\/strong><\/h2><p><span style=\"margin-top: -20px;\">em at\u00e9 5x sem juros<\/span><\/p><p>O PASSAPORTE BRONZE dar\u00e1 a voc\u00ea o direito de assistir <strong>todos os jogos do elefante em casa no Paulist\u00e3o 2024 na \u00e1rea GERAL do est\u00e1dio<\/strong>.<\/p><p style=\"text-align: left;\">Garanta j\u00e1 seus ingressos na secretaria do clube ou pelo WhatsApp!<\/p><p>A retirada de todos os ingressos estar\u00e1 dispon\u00edvel na secretaria do Gilbert\u00e3o a partir do dia 08\/01\/2024.<\/p><p><strong>Hor\u00e1rio de atendimento WhatsApp\/Secretaria:<\/strong> das 8h \u00e0s 18h &#8211; de segunda-feira a sexta-feira e das 8h \u00e0s 12h aos s\u00e1bados.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c38a6e3 elementor-align-left elementor-mobile-align-center elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"c38a6e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/wa.me\/\/551435324467?text=Ola%2C%20tenho%20interesse%20em%20comprar%20o%20passaporte\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Comprar pelo WhatsApp<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-29af66d elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"29af66d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-142651a\" data-id=\"142651a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd6eef6 elementor-alert-info elementor-widget elementor-widget-alert\" data-id=\"cd6eef6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"alert.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-alert\" role=\"alert\">\n\n\t\t\t\t\t\t<span class=\"elementor-alert-title\">Vendas encerradas<\/span>\n\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-alert-description\">As vendas dos passaportes foram encerradas. Aguarde a venda de ingressos avulsos.<\/span>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a1d68e4 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"a1d68e4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5cc591c\" data-id=\"5cc591c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-692e8d8 elementor-widget elementor-widget-image\" data-id=\"692e8d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/07\/cropped-cal_escudo_sem_sombra.png\" class=\"attachment-large size-large wp-image-2850\" alt=\"\" srcset=\"https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/07\/cropped-cal_escudo_sem_sombra.png 512w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/07\/cropped-cal_escudo_sem_sombra-300x300.png 300w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/07\/cropped-cal_escudo_sem_sombra-150x150.png 150w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/07\/cropped-cal_escudo_sem_sombra-100x100.png 100w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/07\/cropped-cal_escudo_sem_sombra-50x50.png 50w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/07\/cropped-cal_escudo_sem_sombra-25x25.png 25w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/07\/cropped-cal_escudo_sem_sombra-90x90.png 90w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/07\/cropped-cal_escudo_sem_sombra-270x270.png 270w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/07\/cropped-cal_escudo_sem_sombra-192x192.png 192w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/07\/cropped-cal_escudo_sem_sombra-180x180.png 180w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/07\/cropped-cal_escudo_sem_sombra-32x32.png 32w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4580935 elementor-widget elementor-widget-heading\" data-id=\"4580935\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">LOJA OFICIAL<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-02e0f9d elementor-widget elementor-widget-text-editor\" data-id=\"02e0f9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>SEG \u00e0 SEX<\/strong> &#8211; 8h \u00e0s 17h | <strong>S\u00c1B<\/strong> &#8211; 8h \u00e0s 12h<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab87f4c elementor-widget elementor-widget-text-editor\" data-id=\"ab87f4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>R. Floriano Peixoto, 1796 &#8211; Loja 8B &#8211; Lins\/SP<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-56d73fe\" data-id=\"56d73fe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b1fa4b elementor-widget elementor-widget-image\" data-id=\"7b1fa4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/07\/cropped-cal_escudo_sem_sombra.png\" class=\"attachment-large size-large wp-image-2850\" alt=\"\" srcset=\"https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/07\/cropped-cal_escudo_sem_sombra.png 512w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/07\/cropped-cal_escudo_sem_sombra-300x300.png 300w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/07\/cropped-cal_escudo_sem_sombra-150x150.png 150w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/07\/cropped-cal_escudo_sem_sombra-100x100.png 100w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/07\/cropped-cal_escudo_sem_sombra-50x50.png 50w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/07\/cropped-cal_escudo_sem_sombra-25x25.png 25w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/07\/cropped-cal_escudo_sem_sombra-90x90.png 90w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/07\/cropped-cal_escudo_sem_sombra-270x270.png 270w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/07\/cropped-cal_escudo_sem_sombra-192x192.png 192w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/07\/cropped-cal_escudo_sem_sombra-180x180.png 180w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2023\/07\/cropped-cal_escudo_sem_sombra-32x32.png 32w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54fbb3e elementor-widget elementor-widget-heading\" data-id=\"54fbb3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">GILBERT\u00c3O<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb6d18d elementor-widget elementor-widget-text-editor\" data-id=\"cb6d18d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>SEG \u00e0 SEX<\/strong> &#8211; 9h \u00e0s 17h | <strong>S\u00c1B<\/strong> &#8211; 9h \u00e0s 12h<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-199047f elementor-widget elementor-widget-text-editor\" data-id=\"199047f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Estadio Gilberto Siqueira Lopes &#8211; Entrada A<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-81e2659\" data-id=\"81e2659\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ddcb962 elementor-widget elementor-widget-image\" data-id=\"ddcb962\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"679\" src=\"https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2024\/10\/logo2-1024x724.png\" class=\"attachment-large size-large wp-image-6223\" alt=\"\" srcset=\"https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2024\/10\/logo2-1024x724.png 1024w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2024\/10\/logo2-300x212.png 300w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2024\/10\/logo2-768x543.png 768w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2024\/10\/logo2-1536x1086.png 1536w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2024\/10\/logo2-2048x1448.png 2048w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2024\/10\/logo2-100x71.png 100w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2024\/10\/logo2-50x35.png 50w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2024\/10\/logo2-25x18.png 25w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5afeff elementor-widget elementor-widget-heading\" data-id=\"a5afeff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">VENDA ONLINE<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64ac9cf elementor-align-center elementor-mobile-align-center elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"64ac9cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/portal.totalticket.com.br\/linense\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Comprar<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b7edaab elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"b7edaab\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c757faf\" data-id=\"c757faf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c84c777 elementor-widget elementor-widget-image\" data-id=\"c84c777\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"378\" src=\"https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2024\/12\/Copinha-Sicredi-2025-1024x403-1.png\" class=\"attachment-large size-large wp-image-6318\" alt=\"\" srcset=\"https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2024\/12\/Copinha-Sicredi-2025-1024x403-1.png 1024w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2024\/12\/Copinha-Sicredi-2025-1024x403-1-300x118.png 300w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2024\/12\/Copinha-Sicredi-2025-1024x403-1-768x302.png 768w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2024\/12\/Copinha-Sicredi-2025-1024x403-1-100x39.png 100w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2024\/12\/Copinha-Sicredi-2025-1024x403-1-50x20.png 50w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2024\/12\/Copinha-Sicredi-2025-1024x403-1-25x10.png 25w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-da38ed1\" data-id=\"da38ed1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5692f1f elementor-widget elementor-widget-heading\" data-id=\"5692f1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">APP BIPFUT<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9692eba elementor-widget elementor-widget-text-editor\" data-id=\"9692eba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol style=\"text-align: left;\"><li><strong>BAIXE<\/strong> o aplicativo na loja de apps do seu celular<\/li><li style=\"text-align: left;\">Fa\u00e7a o <b>RECONHECIMENTO FACIAL<\/b><\/li><li style=\"text-align: left;\">E escolha o jogo do CAL que voc\u00ea quer assistir!<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0551149\" data-id=\"0551149\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b71087f elementor-widget elementor-widget-image\" data-id=\"b71087f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"215\" src=\"https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2024\/12\/bipfut-e1735579478169.png\" class=\"attachment-large size-large wp-image-6320\" alt=\"\" srcset=\"https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2024\/12\/bipfut-e1735579478169.png 512w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2024\/12\/bipfut-e1735579478169-300x126.png 300w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2024\/12\/bipfut-e1735579478169-100x42.png 100w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2024\/12\/bipfut-e1735579478169-50x21.png 50w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2024\/12\/bipfut-e1735579478169-25x10.png 25w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a66fb93 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"a66fb93\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6c1212e\" data-id=\"6c1212e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d16238 elementor-align-center elementor-mobile-align-center elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"7d16238\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=br.com.uzer.bipfut\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-android\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Play Store<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a286feb\" data-id=\"a286feb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed2188b elementor-align-center elementor-mobile-align-center elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"ed2188b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/apps.apple.com\/fr\/app\/bipfut-ingressos-para-futebol\/id6450782534?l=pt-BR\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-apple\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">App Store<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7b43ea7 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"7b43ea7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b9c1c7d\" data-id=\"b9c1c7d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fadda93 elementor-widget-divider--separator-type-pattern elementor-widget-divider--no-spacing elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"fadda93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;xMidYMid meet&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 126 26&#039; fill=&#039;black&#039; stroke=&#039;none&#039;%3E%3Cpath d=&#039;M10.7,6l2.5,2.6l-4,4.3l4,5.4l-2.5,1.9l-4.5-5.2l-3.9,4.2L0.7,17L4,13.1L0,8.6l2.3-1.3l3.9,3.9L10.7,6z M23.9,6.6l4.2,4.5L32,7.2l2.3,1.3l-4,4.5l3.2,3.9L32,19.1l-3.9-3.3l-4.5,4.3l-2.5-1.9l4.4-5.1l-4.2-3.9L23.9,6.6zM73.5,6L76,8.6l-4,4.3l4,5.4l-2.5,1.9l-4.5-5.2l-3.9,4.2L63.5,17l4.1-4.7L63.5,8l2.3-1.3l4.1,3.6L73.5,6z M94,6l2.5,2.6l-4,4.3l4,5.4L94,20.1l-3.9-5l-3.9,4.2L84,17l3.2-3.9L84,8.6l2.3-1.3l3.2,3.9L94,6z M106.9,6l4.5,5.1l3.9-3.9l2.3,1.3l-4,4.5l3.2,3.9l-1.6,2.1l-3.9-4.2l-4.5,5.2l-2.5-1.9l4-5.4l-4-4.3L106.9,6z M53.1,6l2.5,2.6l-4,4.3l4,4.6l-2.5,1.9l-4.5-4.5l-3.5,4.5L43.1,17l3.2-3.9l-4-4.5l2.3-1.3l3.9,3.9L53.1,6z&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf52c61 elementor-widget elementor-widget-heading\" data-id=\"cf52c61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pol\u00edticas sobre os ingressos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44ee0d7 elementor-widget elementor-widget-heading\" data-id=\"44ee0d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Meia entrada<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e46ecfb elementor-widget elementor-widget-text-editor\" data-id=\"e46ecfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Quem tem direito?<\/strong><\/p><p>Estudantes, professores, aposentados, idosos e militares.<\/p><p><strong>Como comprovar?<\/strong><\/p><p>Apresentando os documentos que comprovam o direito.<\/p><ul><li>Estudantes: carteirinha de estudante ou comprovante de matr\u00edcula;<\/li><li>Professores: holerite ou documentos que comprovem o exercicio da fun\u00e7\u00e3o;<\/li><li>Aposentados: carteirinha do INSS e documento de identidade (RG);<\/li><li>Idosos: documento de identidade (RG);<\/li><li>Militares: documentos que comprovem o exercicio da fun\u00e7\u00e3o.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b94d20 elementor-widget elementor-widget-heading\" data-id=\"6b94d20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Crian\u00e7as<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a07d9ee elementor-widget elementor-widget-text-editor\" data-id=\"a07d9ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Crian\u00e7as at\u00e9 12 anos n\u00e3o pagam, mas devem, acompanhados de seus pais ou respons\u00e1veis, retirar os ingressos com o seguran\u00e7a na catraca do est\u00e1dio ao entrar.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ingressos Adquira seu ingresso para curtir os jogos do elefante da noroeste no Gilbert\u00e3o! Passaporte Ouro JOGUE COM A GENTE! Chegou a hora torcedor, precisamos que seja um de nossos jogadores e apoie o Elefante no Paulist\u00e3o 2024. Compre j\u00e1 seu PASSAPORTE OURO para todos os jogos do Linense em casa. R$600,00 em at\u00e9 5x sem juros O PASSAPORTE OURO dar\u00e1 a voc\u00ea o direito de ter uma cadeira com seu nome gravado na \u00e1rea coberta do est\u00e1dio e uma camisa oficial 2024. O n\u00famero selecionado na compra ser\u00e1 o n\u00famero da cadeira que receber\u00e1 seu nome e ficar\u00e1 reservada exclusivamente para voc\u00ea durante todo o campeonato. Garanta j\u00e1 sua cadeira em at\u00e9 5x sem juros e retire seus ingressos e camisa oficial na secretaria do est\u00e1dio Gilbert\u00e3o a partir do dia 08\/01\/2024. Hor\u00e1rio de atendimento WhatsApp\/Secretaria: das 8h \u00e0s 18h &#8211; de segunda-feira a sexta-feira e das 8h \u00e0s 12h aos s\u00e1bados. Ver mapa de cadeiras Comprar pelo WhatsApp Passaporte Prata Compre j\u00e1 seu PASSAPORTE PRATA para todos os jogos do Linense em casa. R$210,00 em at\u00e9 5x sem juros O PASSAPORTE PRATA dar\u00e1 a voc\u00ea o direito de assistir todos os jogos do elefante em casa no Paulist\u00e3o 2024 na \u00e1rea COBERTA do est\u00e1dio. Garanta j\u00e1 seus ingressos na secretaria do clube ou pelo WhatsApp! A retirada de todos os ingressos estar\u00e1 dispon\u00edvel na secretaria do Gilbert\u00e3o a partir do dia 08\/01\/2024. Hor\u00e1rio de atendimento WhatsApp\/Secretaria: das 8h \u00e0s 18h &#8211; de segunda-feira a sexta-feira e das 8h \u00e0s 12h aos s\u00e1bados. Comprar pelo WhatsApp Passaporte Bronze Compre j\u00e1 seu PASSAPORTE BRONZE para todos os jogos do Linense em casa. R$140,00 em at\u00e9 5x sem juros O PASSAPORTE BRONZE dar\u00e1 a voc\u00ea o direito de assistir todos os jogos do elefante em casa no Paulist\u00e3o 2024 na \u00e1rea GERAL do est\u00e1dio. Garanta j\u00e1 seus ingressos na secretaria do clube ou pelo WhatsApp! A retirada de todos os ingressos estar\u00e1 dispon\u00edvel na secretaria do Gilbert\u00e3o a partir do dia 08\/01\/2024. Hor\u00e1rio de atendimento WhatsApp\/Secretaria: das 8h \u00e0s 18h &#8211; de segunda-feira a sexta-feira e das 8h \u00e0s 12h aos s\u00e1bados. Comprar pelo WhatsApp Vendas encerradas As vendas dos passaportes foram encerradas. Aguarde a venda de ingressos avulsos. LOJA OFICIAL SEG \u00e0 SEX &#8211; 8h \u00e0s 17h | S\u00c1B &#8211; 8h \u00e0s 12h R. Floriano Peixoto, 1796 &#8211; Loja 8B &#8211; Lins\/SP GILBERT\u00c3O SEG \u00e0 SEX &#8211; 9h \u00e0s 17h | S\u00c1B &#8211; 9h \u00e0s 12h Estadio Gilberto Siqueira Lopes &#8211; Entrada A VENDA ONLINE Comprar APP BIPFUT BAIXE o aplicativo na loja de apps do seu celular Fa\u00e7a o RECONHECIMENTO FACIAL E escolha o jogo do CAL que voc\u00ea quer assistir! Play Store App Store Pol\u00edticas sobre os ingressos Meia entrada Quem tem direito? Estudantes, professores, aposentados, idosos e militares. Como comprovar? Apresentando os documentos que comprovam o direito. Estudantes: carteirinha de estudante ou comprovante de matr\u00edcula; Professores: holerite ou documentos que comprovem o exercicio da fun\u00e7\u00e3o; Aposentados: carteirinha do INSS e documento de identidade (RG); Idosos: documento de identidade (RG); Militares: documentos que comprovem o exercicio da fun\u00e7\u00e3o. Crian\u00e7as Crian\u00e7as at\u00e9 12 anos n\u00e3o pagam, mas devem, acompanhados de seus pais ou respons\u00e1veis, retirar os ingressos com o seguran\u00e7a na catraca do est\u00e1dio ao entrar.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4862","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/pages\/4862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/comments?post=4862"}],"version-history":[{"count":124,"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/pages\/4862\/revisions"}],"predecessor-version":[{"id":8856,"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/pages\/4862\/revisions\/8856"}],"wp:attachment":[{"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/media?parent=4862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}