{"id":6924,"date":"2025-05-16T22:32:00","date_gmt":"2025-05-17T01:32:00","guid":{"rendered":"https:\/\/calinense.com.br\/NOVOSITE\/?page_id=6924"},"modified":"2026-06-14T19:08:02","modified_gmt":"2026-06-14T22:08:02","slug":"sub-20","status":"publish","type":"page","link":"https:\/\/calinense.com.br\/NOVOSITE\/sub-20\/","title":{"rendered":"Sub-20"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6924\" class=\"elementor elementor-6924\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f36a6a1 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"f36a6a1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ef014b4\" data-id=\"ef014b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d43a179 elementor-widget elementor-widget-heading\" data-id=\"d43a179\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Elenco Sub-20<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9b2fdb2 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"9b2fdb2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-0da7fef\" data-id=\"0da7fef\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b69e95 elementor-widget elementor-widget-image\" data-id=\"3b69e95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"240\" height=\"300\" src=\"https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2025\/12\/modelo-240x300-2.png\" class=\"attachment-large size-large wp-image-7975\" alt=\"\" srcset=\"https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2025\/12\/modelo-240x300-2.png 240w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2025\/12\/modelo-240x300-2-80x100.png 80w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2025\/12\/modelo-240x300-2-40x50.png 40w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2025\/12\/modelo-240x300-2-20x25.png 20w\" sizes=\"(max-width: 240px) 100vw, 240px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e000eda elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"e000eda\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b4db8cd\" data-id=\"b4db8cd\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d7632f elementor-widget elementor-widget-text-editor\" data-id=\"2d7632f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf7314a elementor-widget elementor-widget-text-editor\" data-id=\"cf7314a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>X<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-2394f18\" data-id=\"2394f18\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b004d8b elementor-widget elementor-widget-image\" data-id=\"b004d8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"240\" height=\"300\" src=\"https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2025\/12\/modelo-240x300-2.png\" class=\"attachment-large size-large wp-image-7975\" alt=\"\" srcset=\"https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2025\/12\/modelo-240x300-2.png 240w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2025\/12\/modelo-240x300-2-80x100.png 80w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2025\/12\/modelo-240x300-2-40x50.png 40w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2025\/12\/modelo-240x300-2-20x25.png 20w\" sizes=\"(max-width: 240px) 100vw, 240px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2d95e17 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2d95e17\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ec6000e\" data-id=\"ec6000e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-856c608 elementor-widget elementor-widget-text-editor\" data-id=\"856c608\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa3cbd8 elementor-widget elementor-widget-text-editor\" data-id=\"aa3cbd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>X<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-488476c\" data-id=\"488476c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ffe6a03 elementor-widget elementor-widget-image\" data-id=\"ffe6a03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"240\" height=\"300\" src=\"https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2025\/12\/modelo-240x300-2.png\" class=\"attachment-large size-large wp-image-7975\" alt=\"\" srcset=\"https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2025\/12\/modelo-240x300-2.png 240w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2025\/12\/modelo-240x300-2-80x100.png 80w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2025\/12\/modelo-240x300-2-40x50.png 40w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2025\/12\/modelo-240x300-2-20x25.png 20w\" sizes=\"(max-width: 240px) 100vw, 240px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-43dba1e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"43dba1e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-a964ea2\" data-id=\"a964ea2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6103d71 elementor-widget elementor-widget-text-editor\" data-id=\"6103d71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddf63a2 elementor-widget elementor-widget-text-editor\" data-id=\"ddf63a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>X<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-d76122d\" data-id=\"d76122d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e08fabd elementor-widget elementor-widget-image\" data-id=\"e08fabd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"240\" height=\"300\" src=\"https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2025\/12\/modelo-240x300-2.png\" class=\"attachment-large size-large wp-image-7975\" alt=\"\" srcset=\"https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2025\/12\/modelo-240x300-2.png 240w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2025\/12\/modelo-240x300-2-80x100.png 80w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2025\/12\/modelo-240x300-2-40x50.png 40w, https:\/\/calinense.com.br\/NOVOSITE\/wp-content\/uploads\/2025\/12\/modelo-240x300-2-20x25.png 20w\" sizes=\"(max-width: 240px) 100vw, 240px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9a91b35 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"9a91b35\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-934f6dd\" data-id=\"934f6dd\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2bcdb41 elementor-widget elementor-widget-text-editor\" data-id=\"2bcdb41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ffcc4a elementor-widget elementor-widget-text-editor\" data-id=\"5ffcc4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>X<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Elenco Sub-20 . X . X . X . X<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-6924","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/pages\/6924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/comments?post=6924"}],"version-history":[{"count":43,"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/pages\/6924\/revisions"}],"predecessor-version":[{"id":8713,"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/pages\/6924\/revisions\/8713"}],"wp:attachment":[{"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/media?parent=6924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}