{"id":5575,"date":"2024-01-20T19:11:28","date_gmt":"2024-01-20T22:11:28","guid":{"rendered":"https:\/\/calinense.com.br\/NOVOSITE\/?p=5575"},"modified":"2024-01-20T19:14:42","modified_gmt":"2024-01-20T22:14:42","slug":"nota-oficial-em-resposta-a-recente-manifestacao-externada-pela-torcida-organizada-camisa-12","status":"publish","type":"post","link":"https:\/\/calinense.com.br\/NOVOSITE\/nota-oficial-em-resposta-a-recente-manifestacao-externada-pela-torcida-organizada-camisa-12\/","title":{"rendered":"NOTA OFICIAL EM RESPOSTA \u00c0 RECENTE MANIFESTA\u00c7\u00c3O EXTERNADA PELA TORCIDA ORGANIZADA CAMISA 12"},"content":{"rendered":"<p>Lins-SP, 20 de janeiro de 2024.<\/p>\n<p><strong>NOTA OFICIAL EM RESPOSTA \u00c0 RECENTE MANIFESTA\u00c7\u00c3O EXTERNADA<\/strong><\/p>\n<p><strong>PELA TORCIDA ORGANIZADA CAMISA 12<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>O <strong><u>CLUBE ATL\u00c9TICO LINENSE<\/u>,<\/strong> associa\u00e7\u00e3o desportiva, inscrita no CNPJ\/MF sob o n\u00famero 46.204.202\/0001-56, com sede na Rua Leopoldina, 188, Vila Mafalda, CEP. 16400-528, na cidade de Lins, Estado de S\u00e3o Paulo, neste ato representado por seus atuais Gestores, considerando o conte\u00fado da <strong>\u201cMANIFESTA\u00c7\u00c3O EXPRESSA DA INSTITUI\u00c7\u00c3O GREMIO RECREATIVO ESPORTIVO SOCIAL CULTURAL TORCIDA ORGANIZADA CAMISA 12 DO LINENSE\u201d, <\/strong>entende por necess\u00e1rio pontuar algumas circunst\u00e2ncias que envolvem o presente desta honrosa institui\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p>De in\u00edcio, cumpre dizer que compreendemos que a an\u00e1lise dos torcedores vem carregada de paix\u00e3o, e nem poderia ser diferente, posto ser esse o combust\u00edvel que liga e motiva essa uni\u00e3o de esfor\u00e7os, para o bem da Institui\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p>Tamb\u00e9m n\u00e3o desconhecemos, que as cobran\u00e7as externadas pela <strong>TORCIDA ORGANIZADA <\/strong>visam o bem do Clube, a fim de <em>\u201c&#8230; n\u00e3o fazer um campeonato sofr\u00edvel\u201d, <\/em>como salientado por meio de referida manifesta\u00e7\u00e3o<em>.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Alheio a isso tudo, cumpre-nos dizer que fomos verdadeiramente surpreendidos pelas cobran\u00e7as havidas, n\u00e3o apenas pelo tom adotado, mas ainda, e principalmente, porque alicer\u00e7ado na an\u00e1lise de um \u00fanico jogo, ressalte-se, o primeiro de um campeonato que est\u00e1 em seu in\u00edcio.<\/p>\n<p>&nbsp;<\/p>\n<p>Cobram da atual gest\u00e3o, uma solu\u00e7\u00e3o urgente para <em>\u201cdar corpo a esta equipe para que possa melhor representar as cores Atleticanas do Glorioso Linense\u201d, <\/em>sentenciando os atletas e comiss\u00e3o t\u00e9cnica que aqui est\u00e3o, julgando-os <em>\u201cfr\u00e1gil tecnicamente\u201d.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Novamente, respeitando o entendimento dos subscritores de referida manifesta\u00e7\u00e3o, entendemos tratar-se de uma cobran\u00e7a exacerbada e prematura, e ao que parece, desconectada da realidade do Clube.<\/p>\n<p>&nbsp;<\/p>\n<p>As pessoas que aceitaram assumir a gest\u00e3o do Clube Atl\u00e9tico Linense, num momento de enorme fragilidade, o fizeram exclusivamente por abnegado amor a esta Institui\u00e7\u00e3o. Nada recebem, mas muito renunciam, sejam em suas vidas profissionais, ou mesmo, familiar, para consertar grandes equ\u00edvocos de um passado recente, onde muitos compromissos foram assumidos, por\u00e9m, poucos honrados.<\/p>\n<p>&nbsp;<\/p>\n<p>Visamos sim, o bem do Clube, mas n\u00e3o podemos, para fazer um bom campeonato em 2024, comprometer a sa\u00fade financeira, e quem sabe, at\u00e9 mesmo a continuidade da institui\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p>N\u00e3o nos esquecemos da prec\u00e1ria situa\u00e7\u00e3o financeira do Clube, quando aceitamos esse desafio de assumi-lo para um \u00e1rduo trabalho de reconstru\u00e7\u00e3o, que se ressalte, ainda est\u00e1 longe de se finalizar.<\/p>\n<p>&nbsp;<\/p>\n<p>N\u00e3o vendemos ilus\u00e3o! Preferimos as cobran\u00e7as, ainda que as julguemos exacerbadas e prematuras, a conduzir o Clube para um caminho de maiores dificuldades, ou at\u00e9 mesmo, de encerramento de suas atividades, como chegou bem perto de acontecer num passado ainda muito recente.<\/p>\n<p>&nbsp;<\/p>\n<p>Nosso compromisso \u00e9 devolver a esta Institui\u00e7\u00e3o a condi\u00e7\u00e3o de outrora, onde \u00e9ramos reconhecidos como um Clube correto, e que cumpria pontualmente com os compromissos assumidos. Isso, torcedores, podem acreditar que faremos.<\/p>\n<p>&nbsp;<\/p>\n<p>Cremos, e disso jamais abriremos m\u00e3o, que ao sucesso dentro da quatro linhas precede a organiza\u00e7\u00e3o, o planejamento e muito trabalho, o que, ressalte-se, n\u00e3o est\u00e1 faltando aos atletas que vestem nossa camisa, e entram em campo para bem representar as tradi\u00e7\u00f5es de nosso Clube.<\/p>\n<p>&nbsp;<\/p>\n<p>O trabalho n\u00e3o cessa&#8230; permanecemos, juntos de nossa comiss\u00e3o t\u00e9cnica, atentos \u00e0s necessidades que se apresentam, com a plena certeza de que ao final colheremos os frutos de um trabalho bem feito, com suor e sacrif\u00edcio.<\/p>\n<p>&nbsp;<\/p>\n<p>Finalizamos reafirmando nossa confian\u00e7a na capacidade e compromissos dos atletas que confiaram em nosso projeto e aceitaram o desafio de vestir e bem representar essa gloriosa camisa, convocando aqueles que amam esta Gloriosa Institui\u00e7\u00e3o, que lhes prestem o incondicional apoio, portando-se como verdadeiros aliados nessa luta que apenas se inicia.<\/p>\n<p>&nbsp;<\/p>\n<p>Avante, Linense!<\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>\u201c<\/em><\/strong><strong><em>Nunca julgue um livro pela capa, pois o seu conte\u00fado pode ser surpreendente!<\/em><\/strong><strong><em>\u201d<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lins-SP, 20 de janeiro de 2024. NOTA OFICIAL EM RESPOSTA \u00c0 RECENTE MANIFESTA\u00c7\u00c3O EXTERNADA PELA TORCIDA ORGANIZADA CAMISA 12 &nbsp; O CLUBE ATL\u00c9TICO LINENSE, associa\u00e7\u00e3o desportiva, inscrita no CNPJ\/MF sob o n\u00famero 46.204.202\/0001-56, com sede na Rua Leopoldina, 188, Vila Mafalda, CEP. 16400-528, na cidade de Lins, Estado de S\u00e3o Paulo, neste ato representado por seus atuais Gestores, considerando o conte\u00fado da \u201cMANIFESTA\u00c7\u00c3O EXPRESSA DA INSTITUI\u00c7\u00c3O GREMIO RECREATIVO ESPORTIVO SOCIAL CULTURAL TORCIDA ORGANIZADA CAMISA 12 DO LINENSE\u201d, entende por necess\u00e1rio pontuar algumas circunst\u00e2ncias que envolvem o presente desta honrosa institui\u00e7\u00e3o. &nbsp; De in\u00edcio, cumpre dizer que compreendemos que a an\u00e1lise dos torcedores vem carregada de paix\u00e3o, e nem poderia ser diferente, posto ser esse o combust\u00edvel que liga e motiva essa uni\u00e3o de esfor\u00e7os, para o bem da Institui\u00e7\u00e3o. &nbsp; Tamb\u00e9m n\u00e3o desconhecemos, que as cobran\u00e7as externadas pela TORCIDA ORGANIZADA visam o bem do Clube, a fim de \u201c&#8230; n\u00e3o fazer um campeonato sofr\u00edvel\u201d, como salientado por meio de referida manifesta\u00e7\u00e3o. &nbsp; Alheio a isso tudo, cumpre-nos dizer que fomos verdadeiramente surpreendidos pelas cobran\u00e7as havidas, n\u00e3o apenas pelo tom adotado, mas ainda, e principalmente, porque alicer\u00e7ado na an\u00e1lise de um \u00fanico jogo, ressalte-se, o primeiro de um campeonato que est\u00e1 em seu in\u00edcio. &nbsp; Cobram da atual gest\u00e3o, uma solu\u00e7\u00e3o urgente para \u201cdar corpo a esta equipe para que possa melhor representar as cores Atleticanas do Glorioso Linense\u201d, sentenciando os atletas e comiss\u00e3o t\u00e9cnica que aqui est\u00e3o, julgando-os \u201cfr\u00e1gil tecnicamente\u201d. &nbsp; Novamente, respeitando o entendimento dos subscritores de referida manifesta\u00e7\u00e3o, entendemos tratar-se de uma cobran\u00e7a exacerbada e prematura, e ao que parece, desconectada da realidade do Clube. &nbsp; As pessoas que aceitaram assumir a gest\u00e3o do Clube Atl\u00e9tico Linense, num momento de enorme fragilidade, o fizeram exclusivamente por abnegado amor a esta Institui\u00e7\u00e3o. Nada recebem, mas muito renunciam, sejam em suas vidas profissionais, ou mesmo, familiar, para consertar grandes equ\u00edvocos de um passado recente, onde muitos compromissos foram assumidos, por\u00e9m, poucos honrados. &nbsp; Visamos sim, o bem do Clube, mas n\u00e3o podemos, para fazer um bom campeonato em 2024, comprometer a sa\u00fade financeira, e quem sabe, at\u00e9 mesmo a continuidade da institui\u00e7\u00e3o. &nbsp; N\u00e3o nos esquecemos da prec\u00e1ria situa\u00e7\u00e3o financeira do Clube, quando aceitamos esse desafio de assumi-lo para um \u00e1rduo trabalho de reconstru\u00e7\u00e3o, que se ressalte, ainda est\u00e1 longe de se finalizar. &nbsp; N\u00e3o vendemos ilus\u00e3o! Preferimos as cobran\u00e7as, ainda que as julguemos exacerbadas e prematuras, a conduzir o Clube para um caminho de maiores dificuldades, ou at\u00e9 mesmo, de encerramento de suas atividades, como chegou bem perto de acontecer num passado ainda muito recente. &nbsp; Nosso compromisso \u00e9 devolver a esta Institui\u00e7\u00e3o a condi\u00e7\u00e3o de outrora, onde \u00e9ramos reconhecidos como um Clube correto, e que cumpria pontualmente com os compromissos assumidos. Isso, torcedores, podem acreditar que faremos. &nbsp; Cremos, e disso jamais abriremos m\u00e3o, que ao sucesso dentro da quatro linhas precede a organiza\u00e7\u00e3o, o planejamento e muito trabalho, o que, ressalte-se, n\u00e3o est\u00e1 faltando aos atletas que vestem nossa camisa, e entram em campo para bem representar as tradi\u00e7\u00f5es de nosso Clube. &nbsp; O trabalho n\u00e3o cessa&#8230; permanecemos, juntos de nossa comiss\u00e3o t\u00e9cnica, atentos \u00e0s necessidades que se apresentam, com a plena certeza de que ao final colheremos os frutos de um trabalho bem feito, com suor e sacrif\u00edcio. &nbsp; Finalizamos reafirmando nossa confian\u00e7a na capacidade e compromissos dos atletas que confiaram em nosso projeto e aceitaram o desafio de vestir e bem representar essa gloriosa camisa, convocando aqueles que amam esta Gloriosa Institui\u00e7\u00e3o, que lhes prestem o incondicional apoio, portando-se como verdadeiros aliados nessa luta que apenas se inicia. &nbsp; Avante, Linense! &nbsp; \u201cNunca julgue um livro pela capa, pois o seu conte\u00fado pode ser surpreendente!\u201d<\/p>\n","protected":false},"author":1,"featured_media":5515,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5575","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-profissional"],"_links":{"self":[{"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/posts\/5575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/comments?post=5575"}],"version-history":[{"count":2,"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/posts\/5575\/revisions"}],"predecessor-version":[{"id":5577,"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/posts\/5575\/revisions\/5577"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/media\/5515"}],"wp:attachment":[{"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/media?parent=5575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/categories?post=5575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/tags?post=5575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}