{"id":5643,"date":"2024-02-10T22:15:57","date_gmt":"2024-02-11T01:15:57","guid":{"rendered":"https:\/\/calinense.com.br\/NOVOSITE\/?p=5643"},"modified":"2024-02-14T18:26:27","modified_gmt":"2024-02-14T21:26:27","slug":"linense-vence-o-primavera-no-gilbertao","status":"publish","type":"post","link":"https:\/\/calinense.com.br\/NOVOSITE\/linense-vence-o-primavera-no-gilbertao\/","title":{"rendered":"Linense vence o Primavera no Gilbert\u00e3o"},"content":{"rendered":"<p>O Linense entrou em campo neste s\u00e1bado, e saiu vitorioso diante do Primavera.<\/p>\n<p>O elefante venceu pelo placar de 2 a 1, com dois gols de Jonathan Marino,com o resultado o Linense sobe na classifica\u00e7\u00e3o e segue na briga pelo G8 da competi\u00e7\u00e3o.<\/p>\n<p>O Linense volta a campo no pr\u00f3ximo s\u00e1bado (17\/02), \u00e0s 17h onde enfrenta a Ferrovi\u00e1ria em Araraquara.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Linense entrou em campo neste s\u00e1bado, e saiu vitorioso diante do Primavera. O elefante venceu pelo placar de 2 a 1, com dois gols de Jonathan Marino,com o resultado o Linense sobe na classifica\u00e7\u00e3o e segue na briga pelo G8 da competi\u00e7\u00e3o. O Linense volta a campo no pr\u00f3ximo s\u00e1bado (17\/02), \u00e0s 17h onde enfrenta a Ferrovi\u00e1ria em Araraquara.<\/p>\n","protected":false},"author":1,"featured_media":5644,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5643","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-profissional"],"_links":{"self":[{"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/posts\/5643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/comments?post=5643"}],"version-history":[{"count":1,"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/posts\/5643\/revisions"}],"predecessor-version":[{"id":5645,"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/posts\/5643\/revisions\/5645"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/media\/5644"}],"wp:attachment":[{"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/media?parent=5643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/categories?post=5643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/calinense.com.br\/NOVOSITE\/wp-json\/wp\/v2\/tags?post=5643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}